{"id":373,"date":"2015-01-14T12:12:55","date_gmt":"2015-01-14T04:12:55","guid":{"rendered":"http:\/\/www.ppukm.ukm.my\/oftalmologi\/?page_id=373"},"modified":"2026-04-01T11:09:24","modified_gmt":"2026-04-01T03:09:24","slug":"carta-organisasi","status":"publish","type":"page","link":"https:\/\/www.ukm.my\/oftalmologifper\/carta-organisasi\/","title":{"rendered":"Carta Organisasi"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-3011 size-full\" src=\"http:\/\/www.ukm.my\/oftalmologifper\/wp-content\/uploads\/2026\/04\/Carta-Organisasi-26.01.26.png\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/www.ukm.my\/oftalmologifper\/wp-content\/uploads\/2026\/04\/Carta-Organisasi-26.01.26.png 960w, https:\/\/www.ukm.my\/oftalmologifper\/wp-content\/uploads\/2026\/04\/Carta-Organisasi-26.01.26-300x225.png 300w, https:\/\/www.ukm.my\/oftalmologifper\/wp-content\/uploads\/2026\/04\/Carta-Organisasi-26.01.26-768x576.png 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><em>View in PDF<\/em>: <a href=\"http:\/\/www.ukm.my\/oftalmologifper\/wp-content\/uploads\/2026\/04\/Carta-Organisasi-26.01.26.pdf\">Carta Organisasi Jabatan Oftalmologi (Jan2026)<\/a><img decoding=\"async\" class=\"aligncenter size-full wp-image-1081\" src=\"http:\/\/www.ppukm.ukm.my\/oftalmologi\/wp-content\/uploads\/2018\/10\/CARTA-ORGANISASI-JABATAN-2310208.tif\" alt=\"\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; View in PDF: Carta Organisasi Jabatan Oftalmologi (Jan2026)<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-373","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carta Organisasi - Jabatan Oftalmologi Fakulti Perubatan<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ukm.my\/oftalmologifper\/carta-organisasi\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carta Organisasi - Jabatan Oftalmologi Fakulti Perubatan\" \/>\n<meta property=\"og:description\" content=\"&nbsp; View in PDF: Carta Organisasi Jabatan Oftalmologi (Jan2026)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ukm.my\/oftalmologifper\/carta-organisasi\/\" \/>\n<meta property=\"og:site_name\" content=\"Jabatan Oftalmologi Fakulti Perubatan\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-01T03:09:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ukm.my\/oftalmologifper\/wp-content\/uploads\/2026\/04\/Carta-Organisasi-26.01.26.png\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ukm.my\\\/oftalmologifper\\\/carta-organisasi\\\/\",\"url\":\"https:\\\/\\\/www.ukm.my\\\/oftalmologifper\\\/carta-organisasi\\\/\",\"name\":\"Carta Organisasi - Jabatan Oftalmologi Fakulti Perubatan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ukm.my\\\/oftalmologifper\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ukm.my\\\/oftalmologifper\\\/carta-organisasi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ukm.my\\\/oftalmologifper\\\/carta-organisasi\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.ukm.my\\\/oftalmologifper\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Carta-Organisasi-26.01.26.png\",\"datePublished\":\"2015-01-14T04:12:55+00:00\",\"dateModified\":\"2026-04-01T03:09:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ukm.my\\\/oftalmologifper\\\/carta-organisasi\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ukm.my\\\/oftalmologifper\\\/carta-organisasi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ukm.my\\\/oftalmologifper\\\/carta-organisasi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ukm.my\\\/oftalmologifper\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Carta-Organisasi-26.01.26.png\",\"contentUrl\":\"https:\\\/\\\/www.ukm.my\\\/oftalmologifper\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Carta-Organisasi-26.01.26.png\",\"width\":960,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ukm.my\\\/oftalmologifper\\\/carta-organisasi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ukm.my\\\/oftalmologifper\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carta Organisasi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ukm.my\\\/oftalmologifper\\\/#website\",\"url\":\"https:\\\/\\\/www.ukm.my\\\/oftalmologifper\\\/\",\"name\":\"Jabatan Oftalmologi Fakulti Perubatan\",\"description\":\"Universiti Kebangsaan Malaysia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ukm.my\\\/oftalmologifper\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carta Organisasi - Jabatan Oftalmologi Fakulti Perubatan","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ukm.my\/oftalmologifper\/carta-organisasi\/","og_locale":"en_US","og_type":"article","og_title":"Carta Organisasi - Jabatan Oftalmologi Fakulti Perubatan","og_description":"&nbsp; View in PDF: Carta Organisasi Jabatan Oftalmologi (Jan2026)","og_url":"https:\/\/www.ukm.my\/oftalmologifper\/carta-organisasi\/","og_site_name":"Jabatan Oftalmologi Fakulti Perubatan","article_modified_time":"2026-04-01T03:09:24+00:00","og_image":[{"width":960,"height":720,"url":"https:\/\/www.ukm.my\/oftalmologifper\/wp-content\/uploads\/2026\/04\/Carta-Organisasi-26.01.26.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ukm.my\/oftalmologifper\/carta-organisasi\/","url":"https:\/\/www.ukm.my\/oftalmologifper\/carta-organisasi\/","name":"Carta Organisasi - Jabatan Oftalmologi Fakulti Perubatan","isPartOf":{"@id":"https:\/\/www.ukm.my\/oftalmologifper\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ukm.my\/oftalmologifper\/carta-organisasi\/#primaryimage"},"image":{"@id":"https:\/\/www.ukm.my\/oftalmologifper\/carta-organisasi\/#primaryimage"},"thumbnailUrl":"http:\/\/www.ukm.my\/oftalmologifper\/wp-content\/uploads\/2026\/04\/Carta-Organisasi-26.01.26.png","datePublished":"2015-01-14T04:12:55+00:00","dateModified":"2026-04-01T03:09:24+00:00","breadcrumb":{"@id":"https:\/\/www.ukm.my\/oftalmologifper\/carta-organisasi\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ukm.my\/oftalmologifper\/carta-organisasi\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ukm.my\/oftalmologifper\/carta-organisasi\/#primaryimage","url":"https:\/\/www.ukm.my\/oftalmologifper\/wp-content\/uploads\/2026\/04\/Carta-Organisasi-26.01.26.png","contentUrl":"https:\/\/www.ukm.my\/oftalmologifper\/wp-content\/uploads\/2026\/04\/Carta-Organisasi-26.01.26.png","width":960,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.ukm.my\/oftalmologifper\/carta-organisasi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ukm.my\/oftalmologifper\/"},{"@type":"ListItem","position":2,"name":"Carta Organisasi"}]},{"@type":"WebSite","@id":"https:\/\/www.ukm.my\/oftalmologifper\/#website","url":"https:\/\/www.ukm.my\/oftalmologifper\/","name":"Jabatan Oftalmologi Fakulti Perubatan","description":"Universiti Kebangsaan Malaysia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ukm.my\/oftalmologifper\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.ukm.my\/oftalmologifper\/wp-json\/wp\/v2\/pages\/373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ukm.my\/oftalmologifper\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ukm.my\/oftalmologifper\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ukm.my\/oftalmologifper\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ukm.my\/oftalmologifper\/wp-json\/wp\/v2\/comments?post=373"}],"version-history":[{"count":6,"href":"https:\/\/www.ukm.my\/oftalmologifper\/wp-json\/wp\/v2\/pages\/373\/revisions"}],"predecessor-version":[{"id":3013,"href":"https:\/\/www.ukm.my\/oftalmologifper\/wp-json\/wp\/v2\/pages\/373\/revisions\/3013"}],"wp:attachment":[{"href":"https:\/\/www.ukm.my\/oftalmologifper\/wp-json\/wp\/v2\/media?parent=373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}