{"id":731,"date":"2020-04-07T11:39:26","date_gmt":"2020-04-07T03:39:26","guid":{"rendered":"https:\/\/www.ukm.my\/spsfper\/?post_type=clinical_info&#038;p=731"},"modified":"2025-07-02T15:13:46","modified_gmt":"2025-07-02T07:13:46","slug":"fellowship-in-respiratory-medicine-ukm","status":"publish","type":"clinical_info","link":"https:\/\/www.ukm.my\/spsfper\/clinical_info\/fellowship-in-respiratory-medicine-ukm\/","title":{"rendered":"FELLOWSHIP IN RESPIRATORY MEDICINE (UKM)"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"731\" class=\"elementor elementor-731\" data-elementor-post-type=\"clinical_info\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6915e612 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6915e612\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cdbee80\" data-id=\"cdbee80\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3339eb2 elementor-widget elementor-widget-elementskit-accordion\" data-id=\"3339eb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a0416b3eefd2\">\n\n            \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-3339eb2\">\n                        <a href=\"#collapse-b3c8f3c6a0416b3eefd2\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-b3c8f3c6a0416b3eefd2\" aria-expanded=\"false\" aria-controls=\"Collapse-b3c8f3c6a0416b3eefd2\">\n                            \n                            <span class=\"ekit-accordion-title\">Programme Name<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-b3c8f3c6a0416b3eefd2\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-3339eb2\" data-parent=\"#accordion-6a0416b3eefd2\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>FELLOWSHIP IN RESPIRATORY MEDICINE (UKM)<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-3339eb2\">\n                        <a href=\"#collapse-5cb5b066a0416b3eefd2\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-5cb5b066a0416b3eefd2\" aria-expanded=\"false\" aria-controls=\"Collapse-5cb5b066a0416b3eefd2\">\n                            \n                            <span class=\"ekit-accordion-title\">Course Director<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-5cb5b066a0416b3eefd2\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-3339eb2\" data-parent=\"#accordion-6a0416b3eefd2\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p><strong><a href=\"https:\/\/www.ukm.my\/spsfper\/expertukm\/dr-andrea-ban-yu-lin-2\/\" target=\"_blank\" rel=\"noopener\">Assoc. Prof. Dr. Andrea Ban Yu-Lin<\/a><\/strong><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-3339eb2\">\n                        <a href=\"#collapse-71622636a0416b3eefd2\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-71622636a0416b3eefd2\" aria-expanded=\"false\" aria-controls=\"Collapse-71622636a0416b3eefd2\">\n                            \n                            <span class=\"ekit-accordion-title\">Duration of training<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-71622636a0416b3eefd2\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-3339eb2\" data-parent=\"#accordion-6a0416b3eefd2\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>3 years<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-3339eb2\">\n                        <a href=\"#collapse-a360c9c6a0416b3eefd2\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-a360c9c6a0416b3eefd2\" aria-expanded=\"false\" aria-controls=\"Collapse-a360c9c6a0416b3eefd2\">\n                            \n                            <span class=\"ekit-accordion-title\">Training Centres<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-a360c9c6a0416b3eefd2\" class=\" collapse\" aria-labelledby=\"primaryHeading-3-3339eb2\" data-parent=\"#accordion-6a0416b3eefd2\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Hospital Canselor Tuanku Muhriz, Cheras 56000 Kuala Lumpur<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-4-3339eb2\">\n                        <a href=\"#collapse-4a7ec536a0416b3eefd2\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-4a7ec536a0416b3eefd2\" aria-expanded=\"false\" aria-controls=\"Collapse-4a7ec536a0416b3eefd2\">\n                            \n                            <span class=\"ekit-accordion-title\">Eligibility<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-4a7ec536a0416b3eefd2\" class=\" collapse\" aria-labelledby=\"primaryHeading-4-3339eb2\" data-parent=\"#accordion-6a0416b3eefd2\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Recognised postgraduate training in Internal Medicine with interest in Respiratory Medicine<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><!-- \/wp:paragraph --><!-- wp:paragraph --><!-- \/wp:paragraph --><!-- wp:paragraph --><\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-5-3339eb2\">\n                        <a href=\"#collapse-8a938cf6a0416b3eefd2\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-8a938cf6a0416b3eefd2\" aria-expanded=\"false\" aria-controls=\"Collapse-8a938cf6a0416b3eefd2\">\n                            \n                            <span class=\"ekit-accordion-title\">Objectives<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-8a938cf6a0416b3eefd2\" class=\" collapse\" aria-labelledby=\"primaryHeading-5-3339eb2\" data-parent=\"#accordion-6a0416b3eefd2\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>To produce general physicians with detailed knowledge and basic competence and experience in respiratory medicine seen locally.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-6-3339eb2\">\n                        <a href=\"#collapse-e01eb016a0416b3eefd2\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-e01eb016a0416b3eefd2\" aria-expanded=\"false\" aria-controls=\"Collapse-e01eb016a0416b3eefd2\">\n                            \n                            <span class=\"ekit-accordion-title\">Objectives of Programme<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-e01eb016a0416b3eefd2\" class=\" collapse\" aria-labelledby=\"primaryHeading-6-3339eb2\" data-parent=\"#accordion-6a0416b3eefd2\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <ol>\n<li>To produce general phycisians with detailed knowledge in respiratory medicine.<\/li>\n<li>To produce general phycisians with basic competence and experience in performing procedures pertaining to respiratory medicine<\/li>\n<\/ol>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-7-3339eb2\">\n                        <a href=\"#collapse-2ca83c86a0416b3eefd2\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-2ca83c86a0416b3eefd2\" aria-expanded=\"false\" aria-controls=\"Collapse-2ca83c86a0416b3eefd2\">\n                            \n                            <span class=\"ekit-accordion-title\">Activities\/Task<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-2ca83c86a0416b3eefd2\" class=\" collapse\" aria-labelledby=\"primaryHeading-7-3339eb2\" data-parent=\"#accordion-6a0416b3eefd2\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <figure class=\"wp-block-table\">\n<ol>\n<li>Candidate will be required to perform all clinical activities at the level of a specialist i.e. run clinics, do ward rounds, perform simple procedures e.g. bronchoscopy do on-calls.<\/li>\n<li>Candidate should be able and competent to diagnose and manage common respiratory diseases.<\/li>\n<li>Candidate must be confident in interpreting spirometry results, full lung function tests and sleep study results.<\/li>\n<li>Candidate must pass the written and viva examinations which will be held prior to finishing the programme.<\/li>\n<li>Candidates must assist as many procedures as possible and able to perform a few common procedures independently before the final examination.<\/li>\n<li>Candidate must keep a log book and an audit of his\/her performance.<\/li>\n<li>Candidate must be contactable and regularly meet with course director.<\/li>\n<li>Candidate is required to join all clinical and academic activities of the Unit.<\/li>\n<li>Candidate is required to do research during the training and encourage to publish at least 1 manuscript in a WOS journal or present at a local conference.<\/li>\n<\/ol>\n<!-- \/wp:list --><!-- wp:paragraph -->\n<p>\u00a0<\/p>\n<p><strong>Certificate of completion of training certified by Course Director and Dean, Faculty of Medicine UKM will be given to all successful candidates.<\/strong><\/p>\n<\/figure>\n<!-- \/wp:list --><!-- wp:list {\"ordered\":true,\"type\":\"1\",\"start\":4} -->                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-8-3339eb2\">\n                        <a href=\"#collapse-cd418786a0416b3eefd2\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-cd418786a0416b3eefd2\" aria-expanded=\"false\" aria-controls=\"Collapse-cd418786a0416b3eefd2\">\n                            \n                            <span class=\"ekit-accordion-title\">Requirements<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-cd418786a0416b3eefd2\" class=\" collapse\" aria-labelledby=\"primaryHeading-8-3339eb2\" data-parent=\"#accordion-6a0416b3eefd2\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <ol>\n<li>Please apply at least 6 months before intended start date.<\/li>\n<li>You will need Temporary Practising Certificate (TPC) by Malaysian Medical Council (MMC). Please ensure you fulfil all the requirements for TPC. <a href=\"https:\/\/mmc.gov.my\/wp-content\/uploads\/2019\/11\/TPC_July_2019_2.pdf\">https:\/\/mmc.gov.my\/wp-content\/uploads\/2019\/11\/TPC_July_2019_2.pdf<\/a><\/li>\n<li>Application for TPC will be forwarded to MMC by UKM except for Letter of Good Standing.<\/li>\n<\/ol>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                                        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t ","protected":false},"featured_media":0,"template":"","clinicalinformation":[],"class_list":["post-731","clinical_info","type-clinical_info","status-publish","hentry"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.ukm.my\/spsfper\/wp-json\/wp\/v2\/clinical_info\/731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ukm.my\/spsfper\/wp-json\/wp\/v2\/clinical_info"}],"about":[{"href":"https:\/\/www.ukm.my\/spsfper\/wp-json\/wp\/v2\/types\/clinical_info"}],"version-history":[{"count":9,"href":"https:\/\/www.ukm.my\/spsfper\/wp-json\/wp\/v2\/clinical_info\/731\/revisions"}],"predecessor-version":[{"id":8772,"href":"https:\/\/www.ukm.my\/spsfper\/wp-json\/wp\/v2\/clinical_info\/731\/revisions\/8772"}],"wp:attachment":[{"href":"https:\/\/www.ukm.my\/spsfper\/wp-json\/wp\/v2\/media?parent=731"}],"wp:term":[{"taxonomy":"clinicalinformation","embeddable":true,"href":"https:\/\/www.ukm.my\/spsfper\/wp-json\/wp\/v2\/clinicalinformation?post=731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}